{"id":46,"count":16,"description":"","link":"https:\/\/lesjoliescuvees.com\/index.php\/tag\/champagne\/","name":"Champagne","slug":"champagne","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/tags\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts?tags=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}