{"id":6194,"date":"2024-05-06T14:17:02","date_gmt":"2024-05-06T12:17:02","guid":{"rendered":"https:\/\/lesjoliescuvees.com\/?p=6194"},"modified":"2024-05-13T15:40:41","modified_gmt":"2024-05-13T13:40:41","slug":"domaine-de-larlot-jusquau-21-mai","status":"publish","type":"post","link":"https:\/\/lesjoliescuvees.com\/index.php\/2024\/05\/06\/domaine-de-larlot-jusquau-21-mai\/","title":{"rendered":"Domaine de l&rsquo;Arlot &#8211; termin\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le domaine de l&rsquo;<a href=\"https:\/\/www.arlot.com\/\">Arlot<\/a> est de retour sur Les Jolies Cuv\u00e9es avec un g\u00e9n\u00e9reux mill\u00e9sime 2022. Situ\u00e9 principalement sur l&rsquo;appellation Nuits-Saint-Georges, au c\u0153ur de la prestigieuse C\u00f4te de Nuits, il tient son nom du fameux Clos de l&rsquo;Arlot, cr\u00e9\u00e9 au 18\u00e8me si\u00e8cle, et monopole du domaine au m\u00eame titre que le Clos des For\u00eats, tous deux class\u00e9s en 1ers crus. Cette ann\u00e9e, au-del\u00e0 de ces deux monopoles, nous vous proposons deux jolies cuv\u00e9es en Hautes C\u00f4tes et C\u00f4tes de Nuits, ainsi que deux parcelles exceptionnelles : le 1er Cru de Vosne-Roman\u00e9e Les Suchots, et le prestigieux Grand Cru Roman\u00e9e-Saint-Vivant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelques commentaires sur les vins : Le Mont, en blanc, sur les Hautes C\u00f4tes offre une belle salinit\u00e9, frais et fruit\u00e9 avec un peu d&rsquo;exotisme ; le Clos du Chapeau, en rouge est \u00e0 la fois pr\u00eat \u00e0 boire dans sa jeunesse avec son fruit gourmand mais peut se laisser attendre sans probl\u00e8me ; le Clos de l&rsquo;Arlot blanc est l&rsquo;un des blancs les plus originaux et s\u00e9ducteurs de l&rsquo;appellation, avec de tr\u00e8s beaux amers ; son alter ego rouge \u00e0 une belle texture douce et fondue ; le Clos des For\u00eats est tout en puissance et \u00e9l\u00e9gance, avec beaucoup de fraicheur ; Les Suchots \u00e9clate et rayonne, tout en finesse malgr\u00e9 une belle mati\u00e8re ; enfin, le Roman\u00e9e-Saint-Vivant, un des grands crus les plus r\u00e9put\u00e9s de Bourgogne incarne la profondeur de son terroir, avec un potentiel de garde incroyable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le domaine de l&rsquo;Arlot est de retour sur Les Jolies Cuv\u00e9es avec un g\u00e9n\u00e9reux mill\u00e9sime 2022. Situ\u00e9 principalement sur l&rsquo;appellation Nuits-Saint-Georges, au c\u0153ur de la prestigieuse C\u00f4te de Nuits, il tient son nom du fameux Clos de l&rsquo;Arlot, cr\u00e9\u00e9 au 18\u00e8me si\u00e8cle, et monopole du domaine au m\u00eame titre que le Clos des For\u00eats, tous [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[23,428,429,5],"class_list":["post-6194","post","type-post","status-publish","format-standard","hentry","category-ventes","tag-bourgogne","tag-nuits-saint-georges","tag-romanee-saint-vivant","tag-vin-rare"],"_links":{"self":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/6194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/comments?post=6194"}],"version-history":[{"count":5,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/6194\/revisions"}],"predecessor-version":[{"id":6234,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/6194\/revisions\/6234"}],"wp:attachment":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/media?parent=6194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/categories?post=6194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/tags?post=6194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}