{"id":383,"date":"2020-09-12T09:00:19","date_gmt":"2020-09-12T07:00:19","guid":{"rendered":"http:\/\/lesjoliescuvees.com\/?p=383"},"modified":"2020-09-25T20:29:26","modified_gmt":"2020-09-25T18:29:26","slug":"domaine-de-la-soufrandiere-jusquau-25-septembre","status":"publish","type":"post","link":"https:\/\/lesjoliescuvees.com\/index.php\/2020\/09\/12\/domaine-de-la-soufrandiere-jusquau-25-septembre\/","title":{"rendered":"Domaine de La Soufrandi\u00e8re &#8211; termin\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">(<em>Fran\u00e7ois<\/em>) On poursuit cette quinzaine dans le sud de la Bourgogne avec les vins des fameux <a rel=\"noreferrer noopener\" href=\"https:\/\/www.bretbrothers.com\/\" target=\"_blank\">Bret Brothers<\/a> et leur Domaine de la Soufrandi\u00e8re. Le domaine situ\u00e9 \u00e0 Vinzelles appartient \u00e0 la famille Bret depuis 1947. Il s&rsquo;est agrandi petit \u00e0 petit en se focalisant sur les diff\u00e9rentes appellations du M\u00e2connais, notamment la plus connue : Pouilly-Fuiss\u00e9. Les fameux fr\u00e8res de la g\u00e9n\u00e9ration actuelle ont tourn\u00e9 le vignoble vers la biodynamie d\u00e8s le d\u00e9but des ann\u00e9es 2000 et ont lanc\u00e9 en parall\u00e8le le n\u00e9goce Bret Brothers pour \u00e9largir la gamme. Les vins sont d&rsquo;une puret\u00e9 \u00e9clatante et t\u00e9moignent du potentiel de cette partie de la Bourgogne. De nouvelles cuv\u00e9es ont derni\u00e8rement fait leur apparition sous les noms Zen (dose de soufre minimale pour plus de bonheur) et Ovo\u00efde (\u00e9levage en oeuf b\u00e9ton pour une autre expression du Chardonnay). Y&rsquo;a plus qu&rsquo;\u00e0 d\u00e9guster ce beau mill\u00e9sime 2018 !!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Ben) Les fr\u00e8res Bret ne sont plus des inconnus. Ils subliment le M\u00e2connais depuis des ann\u00e9es. M\u00eame quand il se lancent dans la n\u00e9goce et ach\u00e8tent des raisins cultiv\u00e9s en bio sur pied pour les vendanger et les vinifier eux-m\u00eames pour atteindre une qualit\u00e9 \u00e9quivalente \u00e0 la Soufrandi\u00e8re, m\u00eame quand ils se lancent dans des cuv\u00e9es \u00ab\u00a0Zen\u00a0\u00bb avec tr\u00e8s peu de souffre ou \u00ab\u00a0ovo\u00efde\u00a0\u00bb pour utiliser les propri\u00e9t\u00e9s d&rsquo;une autre forme d&rsquo;\u00e9levage&#8230;etc. Bref les mecs ont du talent. Le Clos de Grand-p\u00e8re est net et fin sur un bel \u00e9quilibre agrume\/c\u00e9drat. Le Saint-V\u00e9ran sera plus m\u00fbr et concentr\u00e9 tandis que les Pouilly-Vinzelles sont de grands vins droits et longs au bois\u00e9 sobre surtout sur le climat \u00ab\u00a0Les Quarts\u00a0\u00bb. Enfin, le Pouilly-Fuiss\u00e9 sur le climat \u00ab\u00a0En Chatenay\u00a0\u00bb est min\u00e9ral et \u00e9quilibr\u00e9 caract\u00e9ris\u00e9 par des notes d&rsquo;agrumes, de fruits blancs, de bois\u00e9 fin, d&rsquo;amande am\u00e8re et d&rsquo;aub\u00e9pine qui s&rsquo;\u00e9tire sur une longueur d\u00e9concertante. On est parti sur le \u00ab\u00a0Zen\u00a0\u00bb sur ce vin, car la plupart des d\u00e9gustations pro le notent tr\u00e8s bien et il ne perd apparemment rien de sa superbe avec moins de souffre tant l&rsquo;\u00e9quipe ma\u00eetrise le sujet. En <a rel=\"noreferrer noopener\" href=\"https:\/\/www.bretbrothers.com\/\" target=\"_blank\">Bret Brothers<\/a>, on a s\u00e9lectionn\u00e9 le pouilly-Loch\u00e9 : on est sur une belle mati\u00e8re avec de la poire, du citron, du pamplemousse et des notes de p\u00eache blanche.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/lesjoliescuvees.com\/wp-content\/uploads\/2020\/09\/les.jolies.cuvees.bret_.brothers.pouilly.loche_.colonge.jpg\" alt=\"\" class=\"wp-image-393\"\/><figcaption>Bret Brothers, Pouilly-Loch\u00e9 \u00ab\u00a0La Colonge\u00a0\u00bb, termin\u00e9<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/lesjoliescuvees.com\/wp-content\/uploads\/2020\/09\/les.jolies.cuvees.soufrandiere.pouilly.vinzelles.jpg\" alt=\"\" class=\"wp-image-387\"\/><figcaption>Pouilly-Vinzelles, termin\u00e9<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/lesjoliescuvees.com\/wp-content\/uploads\/2020\/09\/les.jolies.cuvees.soufrandiere.veran_.bonnode.jpg\" alt=\"\" class=\"wp-image-388\"\/><figcaption>Saint-V\u00e9ran \u00ab\u00a0La Bonnode\u00a0\u00bb cuv\u00e9e Ovo\u00efde, termin\u00e9<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/lesjoliescuvees.com\/wp-content\/uploads\/2020\/09\/les.jolies.cuvees.soufrandiere.pouilly.fuisse.chatenay.jpg\" alt=\"\" class=\"wp-image-389\"\/><figcaption>Pouilly-Fuiss\u00e9 \u00ab\u00a0En Chatenay\u00a0\u00bb cuv\u00e9e Zen, termin\u00e9<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/lesjoliescuvees.com\/wp-content\/uploads\/2020\/09\/les.jolies.cuvees.soufrandiere.pouilly.vinzelles.quarts.jpg\" alt=\"\" class=\"wp-image-397\"\/><figcaption>Pouilly-Vinzelles \u00ab\u00a0Les Quarts\u00a0\u00bb, termin\u00e9<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Fran\u00e7ois) On poursuit cette quinzaine dans le sud de la Bourgogne avec les vins des fameux Bret Brothers et leur Domaine de la Soufrandi\u00e8re. Le domaine situ\u00e9 \u00e0 Vinzelles appartient \u00e0 la famille Bret depuis 1947. Il s&rsquo;est agrandi petit \u00e0 petit en se focalisant sur les diff\u00e9rentes appellations du M\u00e2connais, notamment la plus connue [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[10,26,5],"class_list":["post-383","post","type-post","status-publish","format-standard","hentry","category-ventes","tag-biodynamie","tag-macon","tag-vin-rare"],"_links":{"self":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":10,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/383\/revisions"}],"predecessor-version":[{"id":422,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/383\/revisions\/422"}],"wp:attachment":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/media?parent=383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/categories?post=383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/tags?post=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}