{"id":3293,"date":"2022-06-10T14:03:59","date_gmt":"2022-06-10T12:03:59","guid":{"rendered":"https:\/\/lesjoliescuvees.com\/?p=3293"},"modified":"2022-06-20T15:07:39","modified_gmt":"2022-06-20T13:07:39","slug":"le-pays-basque-a-lhonneur-jusquau-20-juin","status":"publish","type":"post","link":"https:\/\/lesjoliescuvees.com\/index.php\/2022\/06\/10\/le-pays-basque-a-lhonneur-jusquau-20-juin\/","title":{"rendered":"Le Pays Basque \u00e0 l&rsquo;honneur &#8211; termin\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Pays Basque est \u00e0 l&rsquo;honneur sur Les Jolies Cuv\u00e9es avec trois domaines de haute qualit\u00e9. Le domaine <a href=\"https:\/\/domaine-arretxea.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Arretxea <\/a>d&rsquo;abord, le plus connu d&rsquo;entre eux, magnifiquement men\u00e9 par la famille Riouspeyrous. Le domaine <a href=\"https:\/\/www.ferme-larraldea.com\/bordaxuria\" target=\"_blank\" rel=\"noreferrer noopener\">Bordaxuria<\/a>, port\u00e9 au sommet par Elorri Recca et Brice Robelet, sur des pentes vertigineuses. Et enfin le domaine <a href=\"http:\/\/www.domainebordatto.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bordatto<\/a>, \u00e0 Jaxu, surtout connu pour ces d\u00e9licieux cidres et vins de pomme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les rouges de chez Arretxea mettent en valeur le potentiel du Tannat, avec une grande buvabilit\u00e9 ; le ros\u00e9 est taill\u00e9 pour la gastronomie ; le rare blanc Hegoxuri est un mod\u00e8le de fraicheur. Le blanc du domaine Bordaxuria est magnifiquement min\u00e9ral. Enfin, la cuv\u00e9e Erotasuna de Bordatto est une originalit\u00e9 dans ces contr\u00e9es pyr\u00e9n\u00e9ennes avec l&rsquo;utilisation du Marselan, c\u00e9page plus m\u00e9diterran\u00e9en mais tout \u00e0 sa place sur ce secteur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pays Basque est \u00e0 l&rsquo;honneur sur Les Jolies Cuv\u00e9es avec trois domaines de haute qualit\u00e9. Le domaine Arretxea d&rsquo;abord, le plus connu d&rsquo;entre eux, magnifiquement men\u00e9 par la famille Riouspeyrous. Le domaine Bordaxuria, port\u00e9 au sommet par Elorri Recca et Brice Robelet, sur des pentes vertigineuses. Et enfin le domaine Bordatto, \u00e0 Jaxu, surtout [&#8230;]\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[233,5],"class_list":["post-3293","post","type-post","status-publish","format-standard","hentry","category-ventes","tag-irouleguy-2","tag-vin-rare"],"_links":{"self":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/3293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/comments?post=3293"}],"version-history":[{"count":3,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/3293\/revisions"}],"predecessor-version":[{"id":3351,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/posts\/3293\/revisions\/3351"}],"wp:attachment":[{"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/media?parent=3293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/categories?post=3293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lesjoliescuvees.com\/index.php\/wp-json\/wp\/v2\/tags?post=3293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}